{"id":10117,"date":"2025-08-06T15:24:17","date_gmt":"2025-08-06T19:24:17","guid":{"rendered":"https:\/\/certapro.com\/st-joseph\/wood-rot-repair-services-copy\/"},"modified":"2025-08-06T15:34:30","modified_gmt":"2025-08-06T19:34:30","slug":"hardie-board-and-fiber-cement-painting","status":"publish","type":"page","link":"https:\/\/certapro.com\/st-joseph\/hardie-board-and-fiber-cement-painting\/","title":{"rendered":"Hardie Board &#038; Fiber Cement Siding Painting Services"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":67,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-dynamic-fields-full-width.php","meta":{"footnotes":""},"categories":[114],"tags":[],"class_list":["post-10117","page","type-page","status-publish","hentry","category-residential-services"],"acf":[],"_links":{"self":[{"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/pages\/10117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/comments?post=10117"}],"version-history":[{"count":0,"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/pages\/10117\/revisions"}],"wp:attachment":[{"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/media?parent=10117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/categories?post=10117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/certapro.com\/st-joseph\/wp-json\/wp\/v2\/tags?post=10117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}