{"id":1740,"date":"2022-07-08T19:38:58","date_gmt":"2022-07-08T23:38:58","guid":{"rendered":"https:\/\/certapro.com\/boise-metro\/?page_id=1740"},"modified":"2024-06-13T16:37:00","modified_gmt":"2024-06-13T20:37:00","slug":"hardie-board-and-fiber-cement-siding","status":"publish","type":"page","link":"https:\/\/certapro.com\/boise-metro\/hardie-board-and-fiber-cement-siding\/","title":{"rendered":"Hardie Board and Fiber Cement Siding"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":67,"featured_media":1,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-dynamic-fields-full-width.php","meta":{"footnotes":""},"categories":[62,12,59],"tags":[],"class_list":["post-1740","page","type-page","status-publish","has-post-thumbnail","hentry","category-exterior","category-our-services","category-residential-services"],"acf":[],"_links":{"self":[{"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/pages\/1740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/comments?post=1740"}],"version-history":[{"count":0,"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/pages\/1740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/media?parent=1740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/categories?post=1740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/certapro.com\/boise-metro\/wp-json\/wp\/v2\/tags?post=1740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}